{"id":4337,"date":"2026-08-21T12:57:58","date_gmt":"2026-08-21T09:57:58","guid":{"rendered":"https:\/\/empori.ai\/informativa-sulla-privacy-di-empori-ai\/"},"modified":"2026-08-28T11:27:20","modified_gmt":"2026-08-28T08:27:20","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/empori.ai\/it\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4337\" class=\"elementor elementor-4337 elementor-4304\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce31d26 e-con-full e-flex e-con e-parent\" data-id=\"ce31d26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-94a3f5a e-con-full e-flex e-con e-child\" data-id=\"94a3f5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8e54f62 e-con-full e-flex e-con e-child\" data-id=\"8e54f62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c80ca9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4c80ca9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Informativa sulla Privacy di empori.ai\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c79d53f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c79d53f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questa Applicazione raccoglie alcuni Dati Personali dei propri Utenti.<\/p><p>Dati Personali trattati per le seguenti finalit\u00e0 e mediante i seguenti servizi:<\/p><h2>Accesso agli account su servizi terzi<\/h2><h3>Accesso all&#8217;account Stripe<\/h3><p>Dati Personali: indirizzo email; nome; cognome; informazioni di pagamento; Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Statistica<\/h2><h3>Google Analytics 4<\/h3><p>Dati Personali: numero di Utenti; statistiche della sessione; Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Contattare l&#8217;Utente<\/h2><h3>Modulo di contatto<\/h3><p>Dati Personali: indirizzo email; Dati di utilizzo<\/p><h3>Mailing list o newsletter<\/h3><p>Dati Personali: indirizzo email; Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Visualizzazione di contenuti da piattaforme esterne<\/h2><h3>Google Fonts<\/h3><p>Dati Personali: Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Gestione dei pagamenti<\/h2><h3>Stripe<\/h3><p>Dati Personali: indirizzo email; nome; cognome; Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Gestione contatti e invio di messaggi<\/h2><h3>HubSpot Email<\/h3><p>Dati Personali: indirizzo email; Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Protezione dallo spam e dai bot<\/h2><h3>Cloudflare Bot Management<\/h3><p>Dati Personali: informazioni sull&#8217;applicazione; aperture dell&#8217;Applicazione; informazioni sul browser; cronologia di navigazione; citt\u00e0; clic; paese; contea; eventi personalizzati; informazioni sul dispositivo; log di dispositivo; geografia\/regione; eventi di interazione; indirizzo IP; eventi della tastiera; lingua; latitudine (della citt\u00e0); avvii; longitudine (della citt\u00e0); area metropolitana; eventi dei sensori di movimento; movimenti del mouse; numero di sessioni; sistemi operativi; eventi di pagina; visualizzazioni di pagina; provincia; posizione di scorrimento; interazioni di scorrimento della pagina; cronologia di ricerca; durata della sessione; statistiche della sessione; stato; eventi touch; Strumenti di Tracciamento; Dati di utilizzo; visualizzazioni video; codice postale (CAP)<\/p><h2>Gestione dei tag<\/h2><h3>Google Tag Manager<\/h3><p>Dati Personali: Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Ottimizzazione e distribuzione del traffico<\/h2><h3>Cloudflare<\/h3><p>Dati Personali: Strumenti di Tracciamento; varie tipologie di Dati secondo quanto specificato dalla privacy policy del servizio<\/p><h3>Bunny CDN<\/h3><p>Dati Personali: Dati di utilizzo<\/p><h2>Gestione del database utenti<\/h2><h3>HubSpot CRM<\/h3><p>Dati Personali: indirizzo email; nome; cognome; Strumenti di Tracciamento; Dati di utilizzo<\/p><h2>Informazioni su come disattivare la pubblicit\u00e0 basata sugli interessi<\/h2><p>Oltre a qualsiasi funzionalit\u00e0 di opt-out fornita da uno qualsiasi dei servizi elencati in questo documento, gli Utenti possono scoprire di pi\u00f9 su come disattivare in generale la pubblicit\u00e0 basata sugli interessi all&#8217;interno della sezione dedicata dell&#8217;Informativa sui Cookie.<\/p><h2>Informazioni di contatto<\/h2><h3>Titolare del Trattamento dei Dati<\/h3><p>Empori AI LLC &#8211; 5307 Victoria Drive #439, Vancouver, BC V5P 3V6, Canada<br\/>Email di contatto del Titolare: info@empori.ai<br\/>Ultimo aggiornamento: 14 luglio 2025<br\/>Questo documento \u00e8 stato creato con il Generatore di Privacy e Cookie Policy di iubenda. Vedi anche il Generatore di Termini e Condizioni. iubenda ospita questo contenuto e raccoglie solo i Dati Personali strettamente necessari per la sua erogazione.<br\/>Mostra l&#8217;Informativa sulla Privacy completa  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informativa sulla Privacy di empori.ai Questa Applicazione raccoglie alcuni Dati &#8230; <a title=\"Privacy Policy\" class=\"read-more\" href=\"https:\/\/empori.ai\/it\/privacy-policy\/\" aria-label=\"Per saperne di pi\u00f9 su Privacy Policy\">Leggi tutto<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4337","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Empori AI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/empori.ai\/it\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Empori AI\" \/>\n<meta property=\"og:description\" content=\"Informativa sulla Privacy di empori.ai Questa Applicazione raccoglie alcuni Dati ... Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/empori.ai\/it\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Empori AI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T08:27:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/empori.ai\\\/it\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Empori AI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/#website\"},\"datePublished\":\"2026-08-21T09:57:58+00:00\",\"dateModified\":\"2026-08-28T08:27:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/empori.ai\\\/it\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/empori.ai\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/empori.ai\\\/it\\\/\",\"name\":\"Empori AI\",\"description\":\"Probably the best Ai for hotels\",\"publisher\":{\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/empori.ai\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/#organization\",\"name\":\"Empori AI\",\"url\":\"https:\\\/\\\/empori.ai\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/empori.ai\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-for-dark-background.png\",\"contentUrl\":\"https:\\\/\\\/empori.ai\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-for-dark-background.png\",\"width\":5577,\"height\":1207,\"caption\":\"Empori AI\"},\"image\":{\"@id\":\"https:\\\/\\\/empori.ai\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Empori AI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/empori.ai\/it\/privacy-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy Policy - Empori AI","og_description":"Informativa sulla Privacy di empori.ai Questa Applicazione raccoglie alcuni Dati ... Leggi tutto","og_url":"https:\/\/empori.ai\/it\/privacy-policy\/","og_site_name":"Empori AI","article_modified_time":"2026-08-28T08:27:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/empori.ai\/it\/privacy-policy\/","url":"https:\/\/empori.ai\/it\/privacy-policy\/","name":"Privacy Policy - Empori AI","isPartOf":{"@id":"https:\/\/empori.ai\/it\/#website"},"datePublished":"2026-08-21T09:57:58+00:00","dateModified":"2026-08-28T08:27:20+00:00","breadcrumb":{"@id":"https:\/\/empori.ai\/it\/privacy-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/empori.ai\/it\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/empori.ai\/it\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/empori.ai\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/empori.ai\/it\/#website","url":"https:\/\/empori.ai\/it\/","name":"Empori AI","description":"Probably the best Ai for hotels","publisher":{"@id":"https:\/\/empori.ai\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/empori.ai\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/empori.ai\/it\/#organization","name":"Empori AI","url":"https:\/\/empori.ai\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/empori.ai\/it\/#\/schema\/logo\/image\/","url":"https:\/\/empori.ai\/wp-content\/uploads\/2024\/09\/logo-for-dark-background.png","contentUrl":"https:\/\/empori.ai\/wp-content\/uploads\/2024\/09\/logo-for-dark-background.png","width":5577,"height":1207,"caption":"Empori AI"},"image":{"@id":"https:\/\/empori.ai\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/pages\/4337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/comments?post=4337"}],"version-history":[{"count":4,"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/pages\/4337\/revisions"}],"predecessor-version":[{"id":4363,"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/pages\/4337\/revisions\/4363"}],"wp:attachment":[{"href":"https:\/\/empori.ai\/it\/wp-json\/wp\/v2\/media?parent=4337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}